{"id":23283,"date":"2024-09-18T12:25:35","date_gmt":"2024-09-18T16:25:35","guid":{"rendered":"https:\/\/fluidmgmt.ak-bio.com\/non-classifiee\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/"},"modified":"2025-11-28T08:58:31","modified_gmt":"2025-11-28T13:58:31","slug":"progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique","status":"publish","type":"post","link":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/","title":{"rendered":"Progr\u00e8s dans la gestion des tampons et la formulation de tampons en ligne \u00e0 usage unique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans ce podcast, nous nous sommes entretenus avec Nainesh Shah, ing\u00e9nieur d&rsquo;application senior chez Asahi Kasei Bioprocess, au sujet de la gestion des tampons, notamment des avantages de la formulation de tampons en ligne et des syst\u00e8mes de formulation de tampons en ligne \u00e0 usage unique.<\/p>\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Advancements in Buffer Management and Single Use Inline Buffer Formulation\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/4F3jddUowGgMj3eBJtJhNF?si=6d1cdb4d41214a4d&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size\" style=\"font-size:24px\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/downstreamcolumn.com\/advancements-in-buffer-management-and-single-use-inline-buffer-formulation\/\" style=\"background-color:#002948\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e9sum\u00e9 de l&rsquo;\u00e9pisode complet<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans ce podcast, nous nous sommes entretenus avec Nainesh Shah, ing\u00e9nieur d&rsquo;application senior chez Asahi Kasei Bioprocess, au sujet de la gestion des tampons, notamment des avantages de la formulation de tampons en ligne et des syst\u00e8mes de formulation de tampons en ligne \u00e0 usage unique.<\/p>\n","protected":false},"author":12,"featured_media":20742,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[286],"tags":[],"class_list":["post-23283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcasts-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Progr\u00e8s dans la gestion des tampons et les syst\u00e8mes IBF [PODCAST] (en anglais)<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment la formulation de tampons en ligne et \u00e0 usage unique am\u00e9liore l&#039;efficacit\u00e9, r\u00e9duit l&#039;encombrement et rationalise les bioproc\u00e9d\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progr\u00e8s dans la gestion des tampons et les syst\u00e8mes IBF [PODCAST] (en anglais)\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment la formulation de tampons en ligne et \u00e0 usage unique am\u00e9liore l&#039;efficacit\u00e9, r\u00e9duit l&#039;encombrement et rationalise les bioproc\u00e9d\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/\" \/>\n<meta property=\"og:site_name\" content=\"AK Bio - Fluid Management\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-18T16:25:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-28T13:58:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/09\/Nainesh-Shah-800x320-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Desiree Henry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Desiree Henry\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/\"},\"author\":{\"name\":\"Desiree Henry\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#\\\/schema\\\/person\\\/55c3431e239eb40440776628e1e416a1\"},\"headline\":\"Progr\u00e8s dans la gestion des tampons et la formulation de tampons en ligne \u00e0 usage unique\",\"datePublished\":\"2024-09-18T16:25:35+00:00\",\"dateModified\":\"2025-11-28T13:58:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/\"},\"wordCount\":84,\"publisher\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Nainesh-Shah-800x320-1.png\",\"articleSection\":[\"Podcasts\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/\",\"url\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/\",\"name\":\"Progr\u00e8s dans la gestion des tampons et les syst\u00e8mes IBF [PODCAST] (en anglais)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Nainesh-Shah-800x320-1.png\",\"datePublished\":\"2024-09-18T16:25:35+00:00\",\"dateModified\":\"2025-11-28T13:58:31+00:00\",\"description\":\"D\u00e9couvrez comment la formulation de tampons en ligne et \u00e0 usage unique am\u00e9liore l'efficacit\u00e9, r\u00e9duit l'encombrement et rationalise les bioproc\u00e9d\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Nainesh-Shah-800x320-1.png\",\"contentUrl\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Nainesh-Shah-800x320-1.png\",\"width\":800,\"height\":320,\"caption\":\"Nainesh Shah picture\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/podcasts-fr\\\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Podcasts\",\"item\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/knowledge\\\/category\\\/podcasts-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progr\u00e8s dans la gestion des tampons et la formulation de tampons en ligne \u00e0 usage unique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/\",\"name\":\"AK Bio - Fluid Management\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#organization\",\"name\":\"AK Bio\",\"url\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/blue_ak_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/blue_ak_Logo.svg\",\"width\":197,\"height\":50,\"caption\":\"AK Bio\"},\"image\":{\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asahi-kasei-bioprocess-america\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/#\\\/schema\\\/person\\\/55c3431e239eb40440776628e1e416a1\",\"name\":\"Desiree Henry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bff6591d10d2ed342fffea25361debbb117c5267a50519f5ac8ff73c46e3c08a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bff6591d10d2ed342fffea25361debbb117c5267a50519f5ac8ff73c46e3c08a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bff6591d10d2ed342fffea25361debbb117c5267a50519f5ac8ff73c46e3c08a?s=96&d=mm&r=g\",\"caption\":\"Desiree Henry\"},\"url\":\"https:\\\/\\\/fluidmgmt.ak-bio.com\\\/fr\\\/author\\\/desiree-henryak-bio-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progr\u00e8s dans la gestion des tampons et les syst\u00e8mes IBF [PODCAST] (en anglais)","description":"D\u00e9couvrez comment la formulation de tampons en ligne et \u00e0 usage unique am\u00e9liore l'efficacit\u00e9, r\u00e9duit l'encombrement et rationalise les bioproc\u00e9d\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/","og_locale":"fr_FR","og_type":"article","og_title":"Progr\u00e8s dans la gestion des tampons et les syst\u00e8mes IBF [PODCAST] (en anglais)","og_description":"D\u00e9couvrez comment la formulation de tampons en ligne et \u00e0 usage unique am\u00e9liore l'efficacit\u00e9, r\u00e9duit l'encombrement et rationalise les bioproc\u00e9d\u00e9s.","og_url":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/","og_site_name":"AK Bio - Fluid Management","article_published_time":"2024-09-18T16:25:35+00:00","article_modified_time":"2025-11-28T13:58:31+00:00","og_image":[{"width":800,"height":320,"url":"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/09\/Nainesh-Shah-800x320-1.png","type":"image\/png"}],"author":"Desiree Henry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Desiree Henry"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/#article","isPartOf":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/"},"author":{"name":"Desiree Henry","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#\/schema\/person\/55c3431e239eb40440776628e1e416a1"},"headline":"Progr\u00e8s dans la gestion des tampons et la formulation de tampons en ligne \u00e0 usage unique","datePublished":"2024-09-18T16:25:35+00:00","dateModified":"2025-11-28T13:58:31+00:00","mainEntityOfPage":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/"},"wordCount":84,"publisher":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#organization"},"image":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/#primaryimage"},"thumbnailUrl":"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/09\/Nainesh-Shah-800x320-1.png","articleSection":["Podcasts"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/","url":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/","name":"Progr\u00e8s dans la gestion des tampons et les syst\u00e8mes IBF [PODCAST] (en anglais)","isPartOf":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/#primaryimage"},"image":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/#primaryimage"},"thumbnailUrl":"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/09\/Nainesh-Shah-800x320-1.png","datePublished":"2024-09-18T16:25:35+00:00","dateModified":"2025-11-28T13:58:31+00:00","description":"D\u00e9couvrez comment la formulation de tampons en ligne et \u00e0 usage unique am\u00e9liore l'efficacit\u00e9, r\u00e9duit l'encombrement et rationalise les bioproc\u00e9d\u00e9s.","breadcrumb":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/#primaryimage","url":"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/09\/Nainesh-Shah-800x320-1.png","contentUrl":"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/09\/Nainesh-Shah-800x320-1.png","width":800,"height":320,"caption":"Nainesh Shah picture"},{"@type":"BreadcrumbList","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/podcasts-fr\/progres-dans-la-gestion-des-tampons-et-la-formulation-de-tampons-en-ligne-a-usage-unique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Podcasts","item":"https:\/\/fluidmgmt.ak-bio.com\/fr\/knowledge\/category\/podcasts-fr\/"},{"@type":"ListItem","position":2,"name":"Progr\u00e8s dans la gestion des tampons et la formulation de tampons en ligne \u00e0 usage unique"}]},{"@type":"WebSite","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#website","url":"https:\/\/fluidmgmt.ak-bio.com\/fr\/","name":"AK Bio - Fluid Management","description":"","publisher":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fluidmgmt.ak-bio.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#organization","name":"AK Bio","url":"https:\/\/fluidmgmt.ak-bio.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/04\/blue_ak_Logo.svg","contentUrl":"https:\/\/fluidmgmt.ak-bio.com\/wp-content\/uploads\/2024\/04\/blue_ak_Logo.svg","width":197,"height":50,"caption":"AK Bio"},"image":{"@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/asahi-kasei-bioprocess-america\/"]},{"@type":"Person","@id":"https:\/\/fluidmgmt.ak-bio.com\/fr\/#\/schema\/person\/55c3431e239eb40440776628e1e416a1","name":"Desiree Henry","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bff6591d10d2ed342fffea25361debbb117c5267a50519f5ac8ff73c46e3c08a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bff6591d10d2ed342fffea25361debbb117c5267a50519f5ac8ff73c46e3c08a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bff6591d10d2ed342fffea25361debbb117c5267a50519f5ac8ff73c46e3c08a?s=96&d=mm&r=g","caption":"Desiree Henry"},"url":"https:\/\/fluidmgmt.ak-bio.com\/fr\/author\/desiree-henryak-bio-com\/"}]}},"_links":{"self":[{"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/posts\/23283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/comments?post=23283"}],"version-history":[{"count":0,"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/posts\/23283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/media\/20742"}],"wp:attachment":[{"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/media?parent=23283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/categories?post=23283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fluidmgmt.ak-bio.com\/fr\/wp-json\/wp\/v2\/tags?post=23283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}